{"id":6897,"date":"2026-07-13T13:21:01","date_gmt":"2026-07-13T13:21:01","guid":{"rendered":"https:\/\/ultratag.eu\/offre-de-reprise-de-systeme-de-laser-tag\/"},"modified":"2026-08-20T11:27:35","modified_gmt":"2026-08-20T11:27:35","slug":"offre-de-reprise-de-systeme-de-laser-tag","status":"publish","type":"page","link":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/","title":{"rendered":"Offre de reprise de syst\u00e8me de laser tag"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_0 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_0 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_0 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--9c893687-ec67-4d71-bd14-51846ddf40ec\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Offre de reprise<\/h4><\/div><\/div>\n\n<div class=\"et_pb_divider_0 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_1 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--5cc275b2-b54a-44e7-a32c-abf79622799f\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">Mettez \u00e0 niveau votre syst\u00e8me de laser game<\/h1><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_2 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>G\u00e9rer un centre de laser tag avec un \u00e9quipement peu fiable ou mal pris en charge peut g\u00e9n\u00e9rer un stress inutile. <\/span><span>Probl\u00e8mes techniques. R\u00e9parations difficiles. Support limit\u00e9. Ou un syst\u00e8me qui ne correspond tout simplement plus \u00e0 la mani\u00e8re dont vous souhaitez exploiter votre centre.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Avec l'offre de reprise UltraTag Lasergames, nous pouvons vous aider \u00e0 explorer les possibilit\u00e9s de passer \u00e0 un syst\u00e8me de laser game fiable, durable et facile \u00e0 utiliser. <\/span><span>Parlez-nous de votre configuration actuelle et nous examinerons les possibilit\u00e9s.<\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--default\" href=\"#offer\">Demandez votre offre de reprise<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_3 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_3 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_0 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/laserguns-ultratag-vests.webp\" alt=\"Gilets de laser tag color\u00e9s expos\u00e9s\" title=\"Pistolets laser - Vestes UltraTag\" width=\"551\" height=\"551\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/laserguns-ultratag-vests.webp 551w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/laserguns-ultratag-vests-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 551px, 100vw\" class=\"wp-image-3971\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_4 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_2 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Votre syst\u00e8me de laser game devrait vous aider \u00e0 g\u00e9rer votre entreprise<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Pas la rendre plus compliqu\u00e9e.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Un syst\u00e8me de laser game professionnel est utilis\u00e9 partie apr\u00e8s partie, jour apr\u00e8s jour. Lorsque l'\u00e9quipement devient peu fiable, difficile \u00e0 entretenir ou co\u00fbteux \u00e0 faire fonctionner, il est peut-\u00eatre temps d'envisager vos options. <\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Les syst\u00e8mes UltraTag sont con\u00e7us pour une utilisation r\u00e9elle dans des centres tr\u00e8s fr\u00e9quent\u00e9s.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Mat\u00e9riel durable. Longue dur\u00e9e de vie de la batterie. Logiciel stable. Utilisation facile. Et un service qui reste impliqu\u00e9 longtemps apr\u00e8s l'installation. Sans aucun contrat de service obligatoire ni redevances\/frais annuels, donc pas de co\u00fbts cach\u00e9s.     <\/span><\/p>\n<p><span>Si vous envisagez de remplacer votre syst\u00e8me actuel, nous serons ravis de discuter des possibilit\u00e9s.<\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_1 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_4 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_5 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_1 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1.png\" title=\"Offre de reprise (1)\" width=\"2000\" height=\"2000\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1.png 2000w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1-1280x1280.png 1280w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1-980x980.png 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2000px, 100vw\" class=\"wp-image-6767\" alt=\"Gilets de laser tag color\u00e9s suspendus en rang\u00e9e.\" \/><\/span><\/div>\n\n<div class=\"et_pb_heading_3 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--9c893687-ec67-4d71-bd14-51846ddf40ec\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Pourquoi passer \u00e0 UltraTag Lasergames ?<\/h4><\/div><\/div>\n\n<div class=\"et_pb_heading_4 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Con\u00e7u pour une utilisation quotidienne<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Depuis 2012, UltraTag Lasergames d\u00e9veloppe des syst\u00e8mes de laser game professionnels en mettant l'accent sur la fiabilit\u00e9, la durabilit\u00e9 et la facilit\u00e9 d'utilisation.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Aujourd'hui, les syst\u00e8mes UltraTag (gilet + pistolet) et MiniTag (pistolet seul transparent) sont utilis\u00e9s dans pr\u00e8s de 100 centres \u00e0 travers l'Europe.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Les op\u00e9rateurs choisissent les syst\u00e8mes UltraTag pour :<\/span><\/p>\n<ul data-spread=\"false\">\n<li><span>Mat\u00e9riel durable con\u00e7u pour une utilisation quotidienne intensive<\/span><\/li>\n<li><span>Autonomie de batterie extr\u00eamement longue<\/span><\/li>\n<li><span>Logiciel stable et facile \u00e0 utiliser<\/span><\/li>\n<li><span>Faible maintenance<\/span><\/li>\n<li><span>R\u00e9parations rapides et support \u00e0 distance<\/span><\/li>\n<li><span>Communication personnelle et directe<\/span><\/li>\n<li><span>Syst\u00e8mes UltraTag et MiniTag compatibles<\/span><\/li>\n<li><span>Produit et service 100 % n\u00e9erlandais<\/span><\/li>\n<\/ul>\n<p><span>Notre objectif est simple : moins de stress pour les op\u00e9rateurs et un gameplay fiable pour leurs clients.<\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_2 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_3 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_5 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_6 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_5 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--9c893687-ec67-4d71-bd14-51846ddf40ec\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Pourquoi passer \u00e0 UltraTag Lasergames ?<\/h4><\/div><\/div>\n\n<div class=\"et_pb_divider_3 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_heading_6 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Con\u00e7u pour une utilisation quotidienne<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Depuis 2012, UltraTag Lasergames d\u00e9veloppe des syst\u00e8mes de laser game professionnels en mettant l'accent sur la fiabilit\u00e9, la durabilit\u00e9 et la facilit\u00e9 d'utilisation.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Aujourd'hui, les syst\u00e8mes UltraTag (gilet + pistolet) et MiniTag (pistolet seul transparent) sont utilis\u00e9s dans pr\u00e8s de 100 centres \u00e0 travers l'Europe.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Les op\u00e9rateurs choisissent les syst\u00e8mes UltraTag pour :<\/span><\/p>\n<ul data-spread=\"false\">\n<li><span>Mat\u00e9riel durable con\u00e7u pour une utilisation quotidienne intensive<\/span><\/li>\n<li><span>Autonomie de batterie extr\u00eamement longue<\/span><\/li>\n<li><span>Logiciel stable et facile \u00e0 utiliser<\/span><\/li>\n<li><span>Faible maintenance<\/span><\/li>\n<li><span>R\u00e9parations rapides et support \u00e0 distance<\/span><\/li>\n<li><span>Communication personnelle et directe<\/span><\/li>\n<li><span>Syst\u00e8mes UltraTag et MiniTag compatibles<\/span><\/li>\n<li><span>Produit et service 100 % n\u00e9erlandais<\/span><\/li>\n<\/ul>\n<p><span>Notre objectif est simple : moins de stress pour les op\u00e9rateurs et un gameplay fiable pour leurs clients.<\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_4 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_2 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1.png\" title=\"Offre de reprise (1)\" width=\"2000\" height=\"2000\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1.png 2000w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1-1280x1280.png 1280w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1-980x980.png 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/07\/Trade-In-Offer-1-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2000px, 100vw\" class=\"wp-image-6767\" alt=\"Gilets de laser tag color\u00e9s suspendus en rang\u00e9e.\" \/><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_4 et_pb_section et_section_specialty et_pb_gutters3 et_block_section\"><div class=\"et_pb_row et_block_row\">\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_single et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_3 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2.png\" title=\"Bowling des 4 Vents\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2.png 1200w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2-980x980.png 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" class=\"wp-image-4425\" \/><\/span><\/div>\n\n<div class=\"et_pb_heading_7 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--9c893687-ec67-4d71-bd14-51846ddf40ec\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">De votre syst\u00e8me actuel \u00e0 UltraTag<\/h4><\/div><\/div>\n\n<div class=\"et_pb_heading_8 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Comment cela fonctionne<\/h2><\/div><\/div>\n\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">=<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Parlez-nous de votre syst\u00e8me actuel<\/h4><div class=\"et_pb_blurb_description\"><p>Envoyez-nous quelques informations de base sur votre \u00e9quipement de laser game actuel, y compris la marque, l'\u00e2ge, le nombre d'unit\u00e9s et l'\u00e9tat actuel.<\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">=<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Nous \u00e9valuons votre configuration<\/h4><div class=\"et_pb_blurb_description\"><p>Chaque syst\u00e8me de laser tag et chaque situation sont diff\u00e9rents. Nous examinerons les informations que vous nous fournissez et \u00e9valuerons si votre \u00e9quipement actuel peut \u00eatre \u00e9ligible \u00e0 notre offre de reprise. <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">=<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Recevez votre proposition de reprise<\/h4><div class=\"et_pb_blurb_description\"><p>Si votre syst\u00e8me est \u00e9ligible, nous discuterons des possibilit\u00e9s de reprise et pr\u00e9parerons une proposition bas\u00e9e sur votre \u00e9quipement actuel et le syst\u00e8me UltraTag ou MiniTag dont vous avez besoin.<\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module preset--module--divi-blurb--default\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">=<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Passez \u00e0 l'action<\/h4><div class=\"et_pb_blurb_description\"><p>Pr\u00eat \u00e0 aller de l'avant ? Nous vous aiderons \u00e0 planifier la transition vers votre nouveau syst\u00e8me UltraTag et \u00e0 rendre le passage aussi fluide et pratique que possible.  <strong data-start=\"271\" data-end=\"430\">Du retrait de votre \u00e9quipement existant \u00e0 l'installation et \u00e0 la configuration de votre nouveau syst\u00e8me, nous veillerons \u00e0 ce que votre centre soit pr\u00eat \u00e0 l'action le plus rapidement possible.<\/strong><\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--default\" href=\"#offer\">Demander une offre de reprise<\/a><\/div>\n\n<div class=\"et_pb_divider_5 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et_pb_specialty_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_row_inner_0 et_pb_row_inner et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_inner_0 et_pb_column_inner et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_4 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-setup1.png\" alt=\"Configuration MiniTag1\" title=\"Configuration MiniTag1\" width=\"1000\" height=\"1500\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-setup1.png 1000w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-setup1-980x1470.png 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-setup1-480x720.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" class=\"wp-image-2913\" \/><\/span><\/div>\n\n<div class=\"et_pb_image_5 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-product-11.png\" alt=\"Produit UltraTag 1:1\" title=\"Produit UltraTag 1:1\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-product-11.png 1200w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-product-11-980x980.png 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-product-11-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" class=\"wp-image-3029\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_inner_1 et_pb_column_inner et_pb_column et_pb_column_1_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_6 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2.png\" title=\"Bowling des 4 Vents\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2.png 1200w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2-980x980.png 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/04\/Bowling-des-4-Vents-2-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" class=\"wp-image-4425\" \/><\/span><\/div>\n\n<div class=\"et_pb_image_7 et_pb_image et_pb_module et_block_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-set.webp\" alt=\"Gros plan d&#039;un pistolet MiniTag, un pistolet de laser game transparent\" title=\"MiniTag - Set\" width=\"899\" height=\"1350\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-set.webp 899w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/minitag-set-480x721.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 899px, 100vw\" class=\"wp-image-3961\" \/><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_section_5 et_pb_section et_section_regular et_flex_section\" id=\"offer\">\n<div class=\"et_pb_row_6 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_10 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_row_7 et_pb_row et_pb_row_nested et_flex_row\">\n<div class=\"et_pb_column_11 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_9 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--9c893687-ec67-4d71-bd14-51846ddf40ec\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">Demandez votre offre de reprise<\/h4><\/div><\/div>\n\n<div class=\"et_pb_divider_6 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_contact_form_0 et_pb_contact_form_container clearfix et_pb_module et_flex_module preset--module--divi-contact-form--default\" data-form_unique_num=\"0\" data-form_unique_id=\"6a20ea31-0e01-4534-851a-581d6637645a\" id=\"et_pb_contact_form_6a20ea31-0e01-4534-851a-581d6637645a\"><div class=\"et-pb-contact-message\"><\/div><div class=\"et_pb_contact\"><form class=\"et_pb_contact_form et_flex_module\" method=\"post\" action=\"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/pages\/6897\">\n<div class=\"et_pb_contact_field_0 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"name\" data-type=\"input\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_name_0\">Nom<\/label><input type=\"text\" name=\"et_pb_contact_0_name_0\" id=\"et_pb_contact_0_name_0\" class=\"input\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"name\" placeholder=\"Nom\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_1 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"companyname\" data-type=\"input\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_companyname_1\">Nom de l\u2019entreprise<\/label><input type=\"text\" name=\"et_pb_contact_0_companyname_1\" id=\"et_pb_contact_0_companyname_1\" class=\"input\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"companyname\" placeholder=\"Nom de l\u2019entreprise\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_2 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"email\" data-type=\"email\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_email_2\">Adresse e-mail<\/label><input type=\"text\" name=\"et_pb_contact_0_email_2\" id=\"et_pb_contact_0_email_2\" class=\"input\" data-required_mark=\"required\" data-field_type=\"email\" data-original_id=\"email\" placeholder=\"Adresse e-mail\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_3 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"phone_number\" data-type=\"input\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_phone_number_3\">Num\u00e9ro de t\u00e9l\u00e9phone<\/label><input type=\"text\" name=\"et_pb_contact_0_phone_number_3\" id=\"et_pb_contact_0_phone_number_3\" class=\"input\" data-required_mark=\"not_required\" data-field_type=\"input\" data-original_id=\"phone_number\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_4 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"location\" data-type=\"input\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_location_4\">Ville, Pays<\/label><input type=\"text\" name=\"et_pb_contact_0_location_4\" id=\"et_pb_contact_0_location_4\" class=\"input\" data-required_mark=\"not_required\" data-field_type=\"input\" data-original_id=\"location\" placeholder=\"Ville, Pays\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_5 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"system\" data-type=\"input\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_system_5\">Marque \/ Syst\u00e8me de laser tag actuel<\/label><input type=\"text\" name=\"et_pb_contact_0_system_5\" id=\"et_pb_contact_0_system_5\" class=\"input\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"system\" placeholder=\"Marque \/ Syst\u00e8me de laser tag actuel\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_6 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"units\" data-type=\"input\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_units_6\">Nombre de gilets\/pistolets<\/label><input type=\"text\" name=\"et_pb_contact_0_units_6\" id=\"et_pb_contact_0_units_6\" class=\"input\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"units\" placeholder=\"Nombre de gilets\/pistolets\" title=\"\" value=\"\" \/><\/div>\n\n<div class=\"et_pb_contact_field_7 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"age\" data-type=\"select\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_age_7\">\u00c2ge approximatif du syst\u00e8me actuel <\/label><select name=\"et_pb_contact_0_age_7\" id=\"et_pb_contact_0_age_7\" class=\"et_pb_contact_select input\" data-required_mark=\"required\" data-field_type=\"select\" data-original_id=\"age\"><option value=\"\">\u00c2ge approximatif du syst\u00e8me actuel <\/option><option value=\"Moins de 2 ans\" data-id=\"\">Moins de 2 ans<\/option><option value=\"2-5 ans\" data-id=\"\">2-5 ans<\/option><option value=\"5-10 ans\" data-id=\"\">5-10 ans<\/option><option value=\"Plus de 10 ans\" data-id=\"\">Plus de 10 ans<\/option><option value=\"Incertain\" data-id=\"\">Incertain<\/option><\/select><\/div>\n\n<div class=\"et_pb_contact_field_8 et_pb_contact_field et_pb_module et_flex_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\" data-id=\"state\" data-type=\"select\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_state_8\">\u00c9tat actuel<\/label><select name=\"et_pb_contact_0_state_8\" id=\"et_pb_contact_0_state_8\" class=\"et_pb_contact_select input\" data-required_mark=\"required\" data-field_type=\"select\" data-original_id=\"state\"><option value=\"\">\u00c9tat actuel<\/option><option value=\"Enti\u00e8rement fonctionnel\" data-id=\"\">Enti\u00e8rement fonctionnel<\/option><option value=\"Principalement fonctionnel, avec quelques probl\u00e8mes\" data-id=\"\">Principalement fonctionnel, avec quelques probl\u00e8mes<\/option><option value=\"Probl\u00e8mes techniques r\u00e9guliers\" data-id=\"\">Probl\u00e8mes techniques r\u00e9guliers<\/option><option value=\"Partiellement d\u00e9fectueux\" data-id=\"\">Partiellement d\u00e9fectueux<\/option><option value=\"Actuellement non utilis\u00e9\" data-id=\"\">Actuellement non utilis\u00e9<\/option><\/select><\/div>\n\n<div class=\"et_pb_contact_field_9 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"reason\" data-type=\"checkbox\"><label class=\"et_pb_contact_form_label\">Principales raisons d'envisager un nouveau syst\u00e8me<\/label><input type=\"hidden\" name=\"et_pb_contact_0_reason_9\" class=\"et_pb_checkbox_handle\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><span class=\"et_pb_contact_field_options_wrapper et_pb_field_module_checkbox\"><span class=\"et_pb_contact_field_options_title\">Principales raisons d&#039;envisager un nouveau syst\u00e8me<\/span><span class=\"et_pb_contact_field_options_list\"><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_0\" class=\"input\" value=\"Probl\u00e8mes de fiabilit\u00e9\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_0\"><i><\/i>Probl\u00e8mes de fiabilit\u00e9<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_1\" class=\"input\" value=\"Service ou assistance m\u00e9diocre\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_1\"><i><\/i>Service ou assistance m\u00e9diocre<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_2\" class=\"input\" value=\"R\u00e9parations co\u00fbteuses\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_2\"><i><\/i>R\u00e9parations co\u00fbteuses<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_3\" class=\"input\" value=\"Mat\u00e9riel obsol\u00e8te\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_3\"><i><\/i>Mat\u00e9riel obsol\u00e8te<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_4\" class=\"input\" value=\"Logiciel difficile\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_4\"><i><\/i>Logiciel difficile<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_5\" class=\"input\" value=\"Autonomie de batterie courte\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_5\"><i><\/i>Autonomie de batterie courte<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_6\" class=\"input\" value=\"Extension ou am\u00e9lioration du centre\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_6\"><i><\/i>Extension ou am\u00e9lioration du centre<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_7\" class=\"input\" value=\"Ouverture d&#039;un nouveau site\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_7\"><i><\/i>Ouverture d'un nouveau site<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_reason_9_8\" class=\"input\" value=\"Autre\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"reason\" \/><label for=\"et_pb_contact_0_reason_9_8\"><i><\/i>Autre<\/label><\/span><\/span><\/span><\/div>\n\n<div class=\"et_pb_contact_field_10 et_pb_contact_field et_pb_module et_flex_module et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_12_24_phone\" data-id=\"products\" data-type=\"checkbox\"><label class=\"et_pb_contact_form_label\">Ce qui vous int\u00e9resse ?<\/label><input type=\"hidden\" name=\"et_pb_contact_0_products_10\" class=\"et_pb_checkbox_handle\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"products\" \/><span class=\"et_pb_contact_field_options_wrapper et_pb_field_module_checkbox\"><span class=\"et_pb_contact_field_options_title\">Ce qui vous int\u00e9resse ?<\/span><span class=\"et_pb_contact_field_options_list\"><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_products_10_0\" class=\"input\" value=\"UltraTag (gilet + pistolet)\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"products\" \/><label for=\"et_pb_contact_0_products_10_0\"><i><\/i>UltraTag (gilet + pistolet)<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_products_10_1\" class=\"input\" value=\"MiniTag (pistolet transparent)\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"products\" \/><label for=\"et_pb_contact_0_products_10_1\"><i><\/i>MiniTag (pistolet transparent)<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_products_10_2\" class=\"input\" value=\"Combinaison d&#039;UltraTag + MiniTag\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"products\" \/><label for=\"et_pb_contact_0_products_10_2\"><i><\/i>Combinaison d'UltraTag + MiniTag<\/label><\/span><span class=\"et_pb_contact_field_checkbox\"><input type=\"checkbox\" id=\"et_pb_contact_0_products_10_3\" class=\"input\" value=\"Pas encore certain\" data-required_mark=\"required\" data-field_type=\"checkbox\" data-original_id=\"products\" \/><label for=\"et_pb_contact_0_products_10_3\"><i><\/i>Pas encore certain<\/label><\/span><\/span><\/span><\/div>\n\n<div class=\"et_pb_contact_field_11 et_pb_contact_field et_pb_module et_flex_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\" data-id=\"message\" data-type=\"text\"><label class=\"et_pb_contact_form_label\" for=\"et_pb_contact_0_message_11\">Message (facultatif)<\/label><textarea name=\"et_pb_contact_0_message_11\" id=\"et_pb_contact_0_message_11\" class=\"et_pb_contact_message input\" data-required_mark=\"not_required\" data-field_type=\"text\" data-original_id=\"message\" placeholder=\"Message (facultatif)\"><\/textarea><\/div>\n<input type=\"hidden\" name=\"et_pb_contactform_submit_6a20ea31-0e01-4534-851a-581d6637645a\" value=\"et_contact_proccess\" \/><div class=\"et_contact_bottom_container\"><div class=\"et_pb_contact_right et_pb_contact_field\"><p class=\"clearfix\"><label><span class=\"et_pb_contact_captcha_question\">9 + 14<\/span> = <input type=\"text\" size=\"2\" class=\"input et_pb_contact_captcha\" data-first_digit=\"9\" data-second_digit=\"14\" data-required_mark=\"required\" name=\"et_pb_contact_captcha_6a20ea31-0e01-4534-851a-581d6637645a\" autocomplete=\"off\" \/><\/label><\/p><\/div><div class=\"et_pb_button_wrapper\"><button type=\"submit\" name=\"et_builder_submit_button\" class=\"et_pb_button et_pb_contact_submit\">Submit<\/button><\/div><\/div><input type=\"hidden\" id=\"_wpnonce-et-pb-contact-form-submitted-6a20ea31-0e01-4534-851a-581d6637645a\" name=\"_wpnonce-et-pb-contact-form-submitted-6a20ea31-0e01-4534-851a-581d6637645a\" value=\"a729bc19fe\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr\/wp-json\/wp\/v2\/pages\/6897\" \/><\/form><\/div><\/div>\n\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p><em>La soumission d'une demande de reprise ne garantit pas l'acceptation ou une valeur de reprise sp\u00e9cifique. Toutes les demandes sont \u00e9valu\u00e9es individuellement en fonction de la marque, de l'\u00e2ge, de l'\u00e9tat, de la configuration et de la commercialisation de l'\u00e9quipement. <\/em><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_6 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_8 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_12 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_8 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-green-laser.webp\" alt=\"Un jeune homme portant un gilet de laser tag. Un faisceau laser vert sort d&#039;un pistolet de laser tag.\" title=\"UltraTag - Laser vert\" width=\"500\" height=\"500\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-green-laser.webp 500w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-green-laser-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" class=\"wp-image-3930\" \/><\/span><\/div>\n\n<div class=\"et_pb_heading_10 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Des syst\u00e8mes de laser game adapt\u00e9s \u00e0 votre centre<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Selon votre centre, votre public et votre fonctionnement, vous pouvez passer \u00e0 UltraTag, MiniTag ou une combinaison des deux syst\u00e8mes.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>UltraTag est notre syst\u00e8me professionnel gilet et pistolet, con\u00e7u pour les ar\u00e8nes \u00e0 fort d\u00e9bit et une utilisation quotidienne intensive.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>MiniTag est notre syst\u00e8me l\u00e9ger de pistolet seul, id\u00e9al pour les centres de divertissement familial, les aires de jeux int\u00e9rieures et les concepts de laser game flexibles.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Les deux syst\u00e8mes sont enti\u00e8rement compatibles et peuvent \u00eatre utilis\u00e9s dans la m\u00eame ar\u00e8ne et m\u00eame dans la m\u00eame partie.<\/p>\n<p><\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_7 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_7 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_9 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_13 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_11 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Des syst\u00e8mes de laser game adapt\u00e9s \u00e0 votre centre<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Selon votre centre, votre public et votre fonctionnement, vous pouvez passer \u00e0 UltraTag, MiniTag ou une combinaison des deux syst\u00e8mes.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>UltraTag est notre syst\u00e8me professionnel gilet et pistolet, con\u00e7u pour les ar\u00e8nes \u00e0 fort d\u00e9bit et une utilisation quotidienne intensive.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>MiniTag est notre syst\u00e8me l\u00e9ger de pistolet seul, id\u00e9al pour les centres de divertissement familial, les aires de jeux int\u00e9rieures et les concepts de laser game flexibles.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Les deux syst\u00e8mes sont enti\u00e8rement compatibles et peuvent \u00eatre utilis\u00e9s dans la m\u00eame ar\u00e8ne et m\u00eame dans la m\u00eame partie.<\/p>\n<p><\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_8 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_14 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_9 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-green-laser.webp\" alt=\"Un jeune homme portant un gilet de laser tag. Un faisceau laser vert sort d&#039;un pistolet de laser tag.\" title=\"UltraTag - Laser vert\" width=\"500\" height=\"500\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-green-laser.webp 500w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-green-laser-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 500px, 100vw\" class=\"wp-image-3930\" \/><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_8 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_10 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_15 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_10 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode.webp\" alt=\"Affichage du pistolet laser montrant le mode de service Ultratag\" title=\"ultratag-service-mode\" width=\"2560\" height=\"2560\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode.webp 2560w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode-1280x1280.webp 1280w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode-980x980.webp 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" class=\"wp-image-3997\" \/><\/span><\/div>\n\n<div class=\"et_pb_heading_12 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Vous ne savez pas si votre syst\u00e8me est \u00e9ligible ?<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Nous comprenons que chaque situation est diff\u00e9rente.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>L'\u00e2ge, la marque, l'\u00e9tat et la configuration de votre \u00e9quipement actuel jouent tous un r\u00f4le dans la d\u00e9termination des possibilit\u00e9s.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>C'est pourquoi nous \u00e9valuons chaque demande de reprise individuellement.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Tous les syst\u00e8mes ou \u00e9quipements de laser tag ne sont pas automatiquement \u00e9ligibles \u00e0 la reprise, mais nous nous efforcerons toujours de trouver une bonne solution pour votre situation.<\/span><\/p>\n<p><span>Nous examinerons la situation et vous donnerons une r\u00e9ponse claire et honn\u00eate. <\/p>\n<p><\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_9 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_9 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_11 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_16 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_13 et_pb_heading et_pb_module et_flex_module preset--module--divi-heading--default\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Vous ne savez pas si votre syst\u00e8me est \u00e9ligible ?<\/h2><\/div><\/div>\n\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-text--default\"><div class=\"et_pb_text_inner\"><p class=\"isSelectedEnd\"><span>Nous comprenons que chaque situation est diff\u00e9rente.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>L'\u00e2ge, la marque, l'\u00e9tat et la configuration de votre \u00e9quipement actuel jouent tous un r\u00f4le dans la d\u00e9termination des possibilit\u00e9s.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>C'est pourquoi nous \u00e9valuons chaque demande de reprise individuellement.<\/span><\/p>\n<p class=\"isSelectedEnd\"><span>Tous les syst\u00e8mes ou \u00e9quipements de laser tag ne sont pas automatiquement \u00e9ligibles \u00e0 la reprise, mais nous nous efforcerons toujours de trouver une bonne solution pour votre situation.<\/span><\/p>\n<p><span>Nous examinerons la situation et vous donnerons une r\u00e9ponse claire et honn\u00eate. <\/p>\n<p><\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_10 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_17 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_11 et_pb_image et_pb_module et_flex_module preset--module--divi-image--default\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode.webp\" alt=\"Affichage du pistolet laser montrant le mode de service Ultratag\" title=\"ultratag-service-mode\" width=\"2560\" height=\"2560\" srcset=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode.webp 2560w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode-1280x1280.webp 1280w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode-980x980.webp 980w, https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/ultratag-service-mode-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" class=\"wp-image-3997\" \/><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_10 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_12 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_18 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_accordion_0 et_pb_accordion et_pb_module et_flex_module preset--module--divi-accordion--default\">\n<div class=\"et_pb_heading_14 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--9c893687-ec67-4d71-bd14-51846ddf40ec\"><div class=\"et_pb_heading_container\"><h4 class=\"et_pb_module_header\">FAQ<\/h4><\/div><\/div>\n\n<div class=\"et_pb_divider_11 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module preset--module--divi-divider--default\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_accordion_item_0 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_open et_flex_module preset--module--divi-accordion-item--default\"><h5 class=\"et_pb_toggle_title\">Puis-je \u00e9changer n'importe quelle marque d'\u00e9quipement de laser game ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Vous pouvez soumettre une demande de reprise pour des \u00e9quipements de diff\u00e9rents fabricants. Cependant, toutes les marques, syst\u00e8mes ou configurations ne seront pas automatiquement \u00e9ligibles. Nous \u00e9valuons chaque demande individuellement.  <\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_accordion_item_1 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module preset--module--divi-accordion-item--default\"><h5 class=\"et_pb_toggle_title\">Comment la valeur de reprise est-elle d\u00e9termin\u00e9e ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Les possibilit\u00e9s d\u00e9pendent de plusieurs facteurs, notamment la marque, l'\u00e2ge, l'\u00e9tat, le nombre d'unit\u00e9s et la configuration de votre syst\u00e8me actuel. Apr\u00e8s avoir examin\u00e9 vos informations, nous vous ferons part des options disponibles. <\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_accordion_item_2 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module preset--module--divi-accordion-item--default\"><h5 class=\"et_pb_toggle_title\">Dois-je savoir exactement quel syst\u00e8me UltraTag je veux ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Non. Parlez-nous de votre centre, de votre public et de votre fonctionnement actuel. Nous pouvons vous aider \u00e0 d\u00e9terminer si UltraTag, MiniTag ou une combinaison des deux syst\u00e8mes est le mieux adapt\u00e9.  <\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_accordion_item_3 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module preset--module--divi-accordion-item--default\"><h5 class=\"et_pb_toggle_title\">UltraTag peut-il aider \u00e0 la transition ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Oui. Nous restons impliqu\u00e9s tout au long du processus et vous aidons \u00e0 vous pr\u00e9parer \u00e0 la transition vers votre nouveau syst\u00e8me. Notre objectif est de rendre le passage clair, pratique et g\u00e9rable pour votre exploitation. Nous retirerons l'ancien syst\u00e8me, installerons le nouveau syst\u00e8me UltraTag, formerons votre personnel et veillerons \u00e0 ce que votre exploitation continue de fonctionner.   <\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_accordion_item_4 et_pb_accordion_item et_pb_toggle et_pb_module et_pb_toggle_close et_flex_module preset--module--divi-accordion-item--default\"><h5 class=\"et_pb_toggle_title\">Que se passe-t-il apr\u00e8s la soumission du formulaire ?<\/h5><div class=\"et_pb_toggle_content et_flex_module\"><p>Nous examinerons les informations concernant votre syst\u00e8me actuel et vous contacterons pour discuter de votre situation, des possibilit\u00e9s et des prochaines \u00e9tapes.<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--default\" href=\"#offer\">Demandez votre offre de reprise<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6897","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Offre de reprise de syst\u00e8me de laser tag - UltraTag Lasergames<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offre de reprise de syst\u00e8me de laser tag - UltraTag Lasergames\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/\" \/>\n<meta property=\"og:site_name\" content=\"UltraTag Lasergames\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61584193293629&amp;sk\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-20T11:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/UltraTag-Shared-Image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/offre-de-reprise-de-systeme-de-laser-tag\\\/\",\"url\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/offre-de-reprise-de-systeme-de-laser-tag\\\/\",\"name\":\"Offre de reprise de syst\u00e8me de laser tag - UltraTag Lasergames\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/#website\"},\"datePublished\":\"2026-07-13T13:21:01+00:00\",\"dateModified\":\"2026-08-20T11:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/offre-de-reprise-de-systeme-de-laser-tag\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ultratag.eu\\\/fr\\\/offre-de-reprise-de-systeme-de-laser-tag\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/offre-de-reprise-de-systeme-de-laser-tag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offre de reprise de syst\u00e8me de laser tag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/\",\"name\":\"UltraTag Lasergames\",\"description\":\"Action Starts Here\",\"publisher\":{\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/#organization\",\"name\":\"UltraTag Lasergames\",\"url\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ultratag.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ultratag-logo-11.png\",\"contentUrl\":\"https:\\\/\\\/ultratag.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ultratag-logo-11.png\",\"width\":300,\"height\":300,\"caption\":\"UltraTag Lasergames\"},\"image\":{\"@id\":\"https:\\\/\\\/ultratag.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61584193293629&sk\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offre de reprise de syst\u00e8me de laser tag - UltraTag Lasergames","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/","og_locale":"fr_FR","og_type":"article","og_title":"Offre de reprise de syst\u00e8me de laser tag - UltraTag Lasergames","og_url":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/","og_site_name":"UltraTag Lasergames","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61584193293629&sk","article_modified_time":"2026-08-20T11:27:35+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/ultratag.eu\/wp-content\/uploads\/2026\/03\/UltraTag-Shared-Image.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/","url":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/","name":"Offre de reprise de syst\u00e8me de laser tag - UltraTag Lasergames","isPartOf":{"@id":"https:\/\/ultratag.eu\/fr\/#website"},"datePublished":"2026-07-13T13:21:01+00:00","dateModified":"2026-08-20T11:27:35+00:00","breadcrumb":{"@id":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ultratag.eu\/fr\/offre-de-reprise-de-systeme-de-laser-tag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ultratag.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Offre de reprise de syst\u00e8me de laser tag"}]},{"@type":"WebSite","@id":"https:\/\/ultratag.eu\/fr\/#website","url":"https:\/\/ultratag.eu\/fr\/","name":"UltraTag Lasergames","description":"Action Starts Here","publisher":{"@id":"https:\/\/ultratag.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ultratag.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ultratag.eu\/fr\/#organization","name":"UltraTag Lasergames","url":"https:\/\/ultratag.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ultratag.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ultratag.eu\/wp-content\/uploads\/2022\/08\/ultratag-logo-11.png","contentUrl":"https:\/\/ultratag.eu\/wp-content\/uploads\/2022\/08\/ultratag-logo-11.png","width":300,"height":300,"caption":"UltraTag Lasergames"},"image":{"@id":"https:\/\/ultratag.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61584193293629&sk"]}]}},"_links":{"self":[{"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/pages\/6897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/comments?post=6897"}],"version-history":[{"count":6,"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/pages\/6897\/revisions"}],"predecessor-version":[{"id":7269,"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/pages\/6897\/revisions\/7269"}],"wp:attachment":[{"href":"https:\/\/ultratag.eu\/fr\/wp-json\/wp\/v2\/media?parent=6897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}